{"id":882,"date":"2021-02-02T15:04:02","date_gmt":"2021-02-02T14:04:02","guid":{"rendered":"https:\/\/arendsee.info\/stadt-arendsee\/?page_id=882"},"modified":"2026-05-05T11:44:18","modified_gmt":"2026-05-05T09:44:18","slug":"stellenangebote","status":"publish","type":"page","link":"https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/","title":{"rendered":"Stellenangebote"},"content":{"rendered":"<h2>Stellenangebote<\/h2>\n<p>Unter dieser Rubrik finden Sie aktuelle Stellengebote der Stadt Arendsee (Altmark), deren Eigenbetriebe bzw. Zweckverb\u00e4nde:<\/p>\n<hr \/>\n<p><a href=\"https:\/\/arendsee.info\/stadt-arendsee\/wp-content\/uploads\/sites\/3\/2021\/07\/2018_09_25_Datenschutzhinweise_fuer_Bewerber.pdf\" target=\"_blank\" rel=\"noopener\">Datenschutzhinweise f\u00fcr Bewerber\/-in<\/a> gem\u00e4\u00df Art. 13 DSGVO zur Datenverarbeitung im Bewerbungsverfahren<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stellenangebote Unter dieser Rubrik finden Sie aktuelle Stellengebote der Stadt Arendsee (Altmark), deren Eigenbetriebe bzw. Zweckverb\u00e4nde: Datenschutzhinweise f\u00fcr Bewerber\/-in gem\u00e4\u00df Art. 13 DSGVO zur Datenverarbeitung im Bewerbungsverfahren<\/p>\n","protected":false},"author":2,"featured_media":1621,"parent":959,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-882","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stellenangebote - Stadt Arendsee<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stellenangebote - Stadt Arendsee\" \/>\n<meta property=\"og:description\" content=\"Stellenangebote Unter dieser Rubrik finden Sie aktuelle Stellengebote der Stadt Arendsee (Altmark), deren Eigenbetriebe bzw. Zweckverb\u00e4nde: Datenschutzhinweise f\u00fcr Bewerber\/-in gem\u00e4\u00df Art. 13 DSGVO zur Datenverarbeitung im Bewerbungsverfahren\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt Arendsee\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T09:44:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arendsee.info\/stadt-arendsee\/wp-content\/uploads\/sites\/3\/2021\/11\/Header_Stellenangebote_group.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1364\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/header-menue\\\/stellenangebote\\\/\",\"url\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/header-menue\\\/stellenangebote\\\/\",\"name\":\"Stellenangebote - Stadt Arendsee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/header-menue\\\/stellenangebote\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/header-menue\\\/stellenangebote\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/11\\\/Header_Stellenangebote_group.png\",\"datePublished\":\"2021-02-02T14:04:02+00:00\",\"dateModified\":\"2026-05-05T09:44:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/header-menue\\\/stellenangebote\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/header-menue\\\/stellenangebote\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/header-menue\\\/stellenangebote\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/11\\\/Header_Stellenangebote_group.png\",\"contentUrl\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/11\\\/Header_Stellenangebote_group.png\",\"width\":1364,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/header-menue\\\/stellenangebote\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Header Men\u00fc\",\"item\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/?page_id=959\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stellenangebote\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/#website\",\"url\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/\",\"name\":\"Stadt Arendsee\",\"description\":\"Eine weitere Arendsee Websites Website\",\"publisher\":{\"@id\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/#organization\",\"name\":\"Stadt Arendsee\",\"url\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/10\\\/RZ_Stadt_Arendsee_Logo_210715_Original.png\",\"contentUrl\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/10\\\/RZ_Stadt_Arendsee_Logo_210715_Original.png\",\"width\":1336,\"height\":850,\"caption\":\"Stadt Arendsee\"},\"image\":{\"@id\":\"https:\\\/\\\/arendsee.info\\\/stadt-arendsee\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stellenangebote - Stadt Arendsee","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/","og_locale":"de_DE","og_type":"article","og_title":"Stellenangebote - Stadt Arendsee","og_description":"Stellenangebote Unter dieser Rubrik finden Sie aktuelle Stellengebote der Stadt Arendsee (Altmark), deren Eigenbetriebe bzw. Zweckverb\u00e4nde: Datenschutzhinweise f\u00fcr Bewerber\/-in gem\u00e4\u00df Art. 13 DSGVO zur Datenverarbeitung im Bewerbungsverfahren","og_url":"https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/","og_site_name":"Stadt Arendsee","article_modified_time":"2026-05-05T09:44:18+00:00","og_image":[{"width":1364,"height":600,"url":"https:\/\/arendsee.info\/stadt-arendsee\/wp-content\/uploads\/sites\/3\/2021\/11\/Header_Stellenangebote_group.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/","url":"https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/","name":"Stellenangebote - Stadt Arendsee","isPartOf":{"@id":"https:\/\/arendsee.info\/stadt-arendsee\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/#primaryimage"},"image":{"@id":"https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/#primaryimage"},"thumbnailUrl":"https:\/\/arendsee.info\/stadt-arendsee\/wp-content\/uploads\/sites\/3\/2021\/11\/Header_Stellenangebote_group.png","datePublished":"2021-02-02T14:04:02+00:00","dateModified":"2026-05-05T09:44:18+00:00","breadcrumb":{"@id":"https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/#primaryimage","url":"https:\/\/arendsee.info\/stadt-arendsee\/wp-content\/uploads\/sites\/3\/2021\/11\/Header_Stellenangebote_group.png","contentUrl":"https:\/\/arendsee.info\/stadt-arendsee\/wp-content\/uploads\/sites\/3\/2021\/11\/Header_Stellenangebote_group.png","width":1364,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/arendsee.info\/stadt-arendsee\/header-menue\/stellenangebote\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/arendsee.info\/stadt-arendsee\/"},{"@type":"ListItem","position":2,"name":"Header Men\u00fc","item":"https:\/\/arendsee.info\/stadt-arendsee\/?page_id=959"},{"@type":"ListItem","position":3,"name":"Stellenangebote"}]},{"@type":"WebSite","@id":"https:\/\/arendsee.info\/stadt-arendsee\/#website","url":"https:\/\/arendsee.info\/stadt-arendsee\/","name":"Stadt Arendsee","description":"Eine weitere Arendsee Websites Website","publisher":{"@id":"https:\/\/arendsee.info\/stadt-arendsee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arendsee.info\/stadt-arendsee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/arendsee.info\/stadt-arendsee\/#organization","name":"Stadt Arendsee","url":"https:\/\/arendsee.info\/stadt-arendsee\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/arendsee.info\/stadt-arendsee\/#\/schema\/logo\/image\/","url":"https:\/\/arendsee.info\/stadt-arendsee\/wp-content\/uploads\/sites\/3\/2021\/10\/RZ_Stadt_Arendsee_Logo_210715_Original.png","contentUrl":"https:\/\/arendsee.info\/stadt-arendsee\/wp-content\/uploads\/sites\/3\/2021\/10\/RZ_Stadt_Arendsee_Logo_210715_Original.png","width":1336,"height":850,"caption":"Stadt Arendsee"},"image":{"@id":"https:\/\/arendsee.info\/stadt-arendsee\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/arendsee.info\/stadt-arendsee\/wp-json\/wp\/v2\/pages\/882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arendsee.info\/stadt-arendsee\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arendsee.info\/stadt-arendsee\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arendsee.info\/stadt-arendsee\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arendsee.info\/stadt-arendsee\/wp-json\/wp\/v2\/comments?post=882"}],"version-history":[{"count":133,"href":"https:\/\/arendsee.info\/stadt-arendsee\/wp-json\/wp\/v2\/pages\/882\/revisions"}],"predecessor-version":[{"id":5556,"href":"https:\/\/arendsee.info\/stadt-arendsee\/wp-json\/wp\/v2\/pages\/882\/revisions\/5556"}],"up":[{"embeddable":true,"href":"https:\/\/arendsee.info\/stadt-arendsee\/wp-json\/wp\/v2\/pages\/959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arendsee.info\/stadt-arendsee\/wp-json\/wp\/v2\/media\/1621"}],"wp:attachment":[{"href":"https:\/\/arendsee.info\/stadt-arendsee\/wp-json\/wp\/v2\/media?parent=882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}